{"id":12632,"count":1,"description":"","link":"https:\/\/perfectworld.tokyo\/news\/tag\/%e3%81%8a%e3%81%aa%e3%81%be%e3%81%88%e3%83%90%e3%83%83%e3%82%b8\/","name":"\u304a\u306a\u307e\u3048\u30d0\u30c3\u30b8","slug":"%e3%81%8a%e3%81%aa%e3%81%be%e3%81%88%e3%83%90%e3%83%83%e3%82%b8","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/perfectworld.tokyo\/news\/wp-json\/wp\/v2\/tags\/12632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perfectworld.tokyo\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/perfectworld.tokyo\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/perfectworld.tokyo\/news\/wp-json\/wp\/v2\/posts?tags=12632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}