{"id":1567,"count":1,"description":"","link":"https:\/\/perfectworld.tokyo\/news\/tag\/%e3%82%a2%e3%82%a4%e3%83%89%e3%83%aa%e3%83%83%e3%82%b7%e3%83%a5%e3%82%bb%e3%83%96%e3%83%b3\/","name":"\u30a2\u30a4\u30c9\u30ea\u30c3\u30b7\u30e5\u30bb\u30d6\u30f3","slug":"%e3%82%a2%e3%82%a4%e3%83%89%e3%83%aa%e3%83%83%e3%82%b7%e3%83%a5%e3%82%bb%e3%83%96%e3%83%b3","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/perfectworld.tokyo\/news\/wp-json\/wp\/v2\/tags\/1567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perfectworld.tokyo\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/perfectworld.tokyo\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/perfectworld.tokyo\/news\/wp-json\/wp\/v2\/posts?tags=1567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}